{"id":14912,"date":"2020-02-25T09:50:58","date_gmt":"2020-02-25T08:50:58","guid":{"rendered":"https:\/\/www.itacoilweb.com\/dienstleistungen\/"},"modified":"2024-06-17T17:29:48","modified_gmt":"2024-06-17T15:29:48","slug":"dienstleistungen","status":"publish","type":"page","link":"https:\/\/www.itacoilweb.com\/de\/dienstleistungen\/","title":{"rendered":"Dienstleistungen"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][dfd_heading style=&#8221;style_09&#8243; subtitle=&#8221;&#8221; content_alignment=&#8221;text-left&#8221; module_animation=&#8221;transition.slideRightBigIn&#8221; delimiter_settings=&#8221;delimiter_style:solid|delimiter_width:80|delimiter_height:1&#8243; undefined=&#8221;&#8221; title_font_options=&#8221;tag:h2&#8243; subtitle_font_options=&#8221;tag:div&#8221;]<\/p>\n<h4><span style=\"font-size: 24pt;\">Dienstleistungen<\/span><\/h4>\n<p>[\/dfd_heading][dfd_spacer screen_wide_spacer_size=&#8221;30&#8243; screen_normal_resolution=&#8221;1024&#8243; screen_tablet_resolution=&#8221;800&#8243; screen_mobile_resolution=&#8221;480&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: justify;\"><strong>Kundenspezifische Komponenten<\/strong><\/p>\n<p>Mit einzigartigen propriet\u00e4ren Werkzeugen f\u00fcr Design und Simulation wird die Entwurfszeit auf ein Minimum reduziert und die Zustimmungsrate der ersten durch Design definierten Probenahme betr\u00e4gt rund 99 %.<\/p>\n<p><em>Unser Haupttalent:<br \/>\n<span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/www.itacoilweb.com\/de\/was-sind-llc-resonanz-stromversorgungen\/\" rel=\"noopener\">Resonante Topologien in Stromversorgungen<\/a><\/strong><\/span><br \/>\n<span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/www.itacoilweb.com\/de\/llc-lcc-resonante-topologien\/\" rel=\"noopener\">Resonante Topologien: LLC vs. LCC<\/a><\/strong><\/span><\/em><\/p>\n<p><em>Unsere <\/em><span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/www.itacoilweb.com\/de\/portfolio\/kundenspezifische-produkte\/\" rel=\"noopener\"><em>kundenspezifische Komponenten<\/em><\/a><\/strong><\/span>[\/vc_column_text][dfd_spacer screen_wide_spacer_size=&#8221;60&#8243; screen_normal_resolution=&#8221;1024&#8243; screen_tablet_resolution=&#8221;800&#8243; screen_mobile_resolution=&#8221;480&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;3\/4&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\"><strong>Sicherheits-Vorkonformit\u00e4t<br \/>\n<\/strong><br \/>\nDie versp\u00e4tete Festlegung der Sicherheitsanforderungen ist eine h\u00e4ufige Ursache der Nichtkonformit\u00e4t von Elektronikdesigns.<br \/>\nIn diesen F\u00e4llen ist eine erneute \u00dcberarbeitung des Entwurfs erforderlich, die den Transformator, die Leiterplatte und die EMV-Tests umfasst, was zus\u00e4tzliche Kosten und erhebliche Verz\u00f6gerungen verursacht.<br \/>\nAu\u00dferdem verursachen erh\u00f6hte Abst\u00e4nde an einem Transformator in der Regel die Verschlechterung einiger Parameter und\/oder die Notwendigkeit eines gr\u00f6\u00dferen Transformators.<\/p>\n<p>Dabei ist zu beachten, dass Eintr\u00e4ge wie \u201eentwickelt in \u00dcbereinstimmung mit EN61558\u201c (oder \u00e4hnlich), die manchmal auf Datenbl\u00e4ttern von Transformatoren zu finden sind, nur bis zu einem gewissen Grad gelten.<br \/>\nDie Sicherheitsanforderungen h\u00e4ngen n\u00e4mlich nicht nur von V(Eingang) und V(Ausgang) ab, sondern auch von spezifischen RMS- und sich wiederholenden Spitzenspannungen, die \u00fcber die Wicklungen und \u00fcber die dazwischenliegende Isolierung auftreten.<br \/>\nSie h\u00e4ngen auch von anderen Elementen wie Isolationsmaterialien, Eigenschaften, Schaltfrequenz und Leistung ab.<\/p>\n<p style=\"text-align: justify;\">Durch unsere Beteiligung an der normativen Arbeit von CT96, dem Technischen Komitee f\u00fcr die Norm EN 61558 f\u00fcr Transformatoren, k\u00f6nnen wir eine erstklassige Unterst\u00fctzung bereitstellen.<br \/>\nWir bieten einen Service f\u00fcr die Definition von Creepage, Clearance, DTI und Spannungsfestigkeit nach EN61558-1, EN61558-2-1, EN61558-2-4, EN61558-2-6, EN61558-2-16 (Transformatoren) und EN61347-1, EN61347-2-13 (Beleuchtung) entwickelt.<\/p>\n<p style=\"text-align: justify;\">Die dritte Ausgabe der EN 61558 f\u00fchrt eine zus\u00e4tzliche Klassifizierung nach der \u00dcberspannungskategorie (OVC-I&#8230;IV) ein.<br \/>\nUnser Service ber\u00fccksichtigt die Anforderungen an die OVC Ihrer Ger\u00e4te.<\/p>\n<p style=\"text-align: justify;\">Nicht zuletzt, weil sich die Normen vieler anderer Produkte auf die EN 61558 beziehen, erstreckt sich die Relevanz unseres Service der Sicherheitsvorpr\u00fcfung auf ein breites Spektrum von Anwendungen.<\/p>\n<p>[\/vc_column_text][dfd_spacer screen_wide_spacer_size=&#8221;60&#8243; screen_normal_resolution=&#8221;1024&#8243; screen_tablet_resolution=&#8221;800&#8243; screen_mobile_resolution=&#8221;480&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][dfd_spacer screen_wide_spacer_size=&#8221;50&#8243; screen_normal_resolution=&#8221;1024&#8243; screen_tablet_resolution=&#8221;800&#8243; screen_mobile_resolution=&#8221;480&#8243;][dfd_single_image image=&#8221;17632&#8243;][dfd_spacer screen_wide_spacer_size=&#8221;60&#8243; screen_normal_resolution=&#8221;1024&#8243; screen_tablet_resolution=&#8221;800&#8243; screen_mobile_resolution=&#8221;480&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;3\/4&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\"><strong>EMC-Vorkonformit\u00e4t<\/strong><\/p>\n<p style=\"text-align: justify;\">Die EMI-Themen, die am h\u00e4ufigsten zur \u00dcberarbeitung der Filter und des Layouts eines SMPS f\u00fchren, sind die Nicht\u00fcbereinstimmungen bez\u00fcglich der leitungsgef\u00fchrten St\u00f6rungen durch Stromkabel und bez\u00fcglich der harmonischen Verzerrung des Eingangsstroms (THD).<\/p>\n<p style=\"text-align: justify;\">Wir verf\u00fcgen \u00fcber ein internes Labor, in dem unsere Kunden eine vorl\u00e4ufige Analyse durchf\u00fchren k\u00f6nnen, um die Zeit und Kosten, die f\u00fcr diese Art von Untersuchung oft erheblich sind, zu reduzieren.<\/p>\n<p style=\"text-align: justify;\">Unser Pre-Compliance-Testservice kann die Analyse und m\u00f6gliche Berichterstattung in Bezug auf Folgendes umfassen:<br \/>\n\u2013 Leitungsgef\u00fchrte St\u00f6rungen<br \/>\n\u2013 Lokalisierung von Strahlungsst\u00f6rquellen durch Nahfeldsonden bis zu 2 GHz<br \/>\n\u2013 Harmonischer Gehalt (bis zur 50. Harmonischen)<br \/>\n\u2013 Gesamte harmonische Verzerrung (THD)<br \/>\n\u2013 Leistungsfaktor<\/p>\n<p style=\"text-align: justify;\">Die Tests k\u00f6nnen in Anwesenheit des Designers durchgef\u00fchrt werden, um in Echtzeit die Verbesserungsversuche an Filtern oder anderen Komponenten zu testen.<\/p>\n<p style=\"text-align: justify;\">Es ist jedoch empfehlenswert, dass die Tests von unseren Technikern unabh\u00e4ngig durchgef\u00fchrt werden, da die Dauer lang sein kann und manchmal die Entwicklung von kundenspezifischen Filterspulen erforderlich ist.<\/p>\n<p>[\/vc_column_text][dfd_spacer screen_wide_spacer_size=&#8221;60&#8243; screen_normal_resolution=&#8221;1024&#8243; screen_tablet_resolution=&#8221;800&#8243; screen_mobile_resolution=&#8221;480&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][dfd_single_image image=&#8221;18212&#8243;][dfd_spacer screen_wide_spacer_size=&#8221;60&#8243; screen_normal_resolution=&#8221;1024&#8243; screen_tablet_resolution=&#8221;800&#8243; screen_mobile_resolution=&#8221;480&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;3\/4&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\"><strong>Weitere Tests<\/strong><\/p>\n<p style=\"text-align: justify;\">Wir k\u00f6nnen auch folgende Tests durchf\u00fchren:<br \/>\n\u2013 Verifizierung von Temperaturen mit IR-W\u00e4rmekamera und\/oder Thermoelementen<br \/>\n\u2013 Hochpr\u00e4zise Effizienzmessung<br \/>\n\u2013 Hochpr\u00e4ziser Stand-by\/Nicht-Last-Verbrauchstest<br \/>\n\u2013 \u00dcberpr\u00fcfung der Reaktion auf Einschalten, auf Netz-Transienten- und Haltezeittests<br \/>\n\u2013 Verifizierung des transienten Lastverhaltens<br \/>\n\u2013 Einschaltspannung mit programmierbarem Phasenwinkel<br \/>\n\u2013\u00a0Durchschlagfestigkeit (\u226410KVac)<br \/>\n\u2013 Isolationswiderstand (\u22645G\u03a9)<br \/>\n\u2013 Tests und\/oder thermische Zyklen in einer W\u00e4rme-Kalt-Feucht-Klimakammer (-70\u00b0&#8230;+200\u00b0C).<\/p>\n<p>[\/vc_column_text][dfd_spacer screen_wide_spacer_size=&#8221;60&#8243; screen_normal_resolution=&#8221;1024&#8243; screen_tablet_resolution=&#8221;800&#8243; screen_mobile_resolution=&#8221;480&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][dfd_single_image image=&#8221;17628&#8243;][dfd_spacer screen_wide_spacer_size=&#8221;60&#8243; screen_normal_resolution=&#8221;1024&#8243; screen_tablet_resolution=&#8221;800&#8243; screen_mobile_resolution=&#8221;480&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;3\/4&#8243;][vc_column_text]<strong>Schnelles Prototyping<\/strong><\/p>\n<p>Die Prototypen werden sowohl in unserer italienischen Produktionsst\u00e4tte als auch in den asiatischen Produktionsst\u00e4tten hergestellt, wodurch die Zeiten erheblich verk\u00fcrzt werden.<br \/>\nMit Hilfe eines hochaufl\u00f6senden 3D-Druckers k\u00f6nnen wir hausintern spezielle Kunststoffteile herstellen.<\/p>\n<p>Dadurch werden die Tests wesentlich beschleunigt und eine optimale Entwicklung der Form erm\u00f6glicht.[\/vc_column_text][dfd_spacer screen_wide_spacer_size=&#8221;60&#8243; screen_normal_resolution=&#8221;1024&#8243; screen_tablet_resolution=&#8221;800&#8243; screen_mobile_resolution=&#8221;480&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][dfd_single_image image=&#8221;17584&#8243;][dfd_spacer screen_wide_spacer_size=&#8221;60&#8243; screen_normal_resolution=&#8221;1024&#8243; screen_tablet_resolution=&#8221;800&#8243; screen_mobile_resolution=&#8221;480&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;3\/4&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\"><strong>Service f\u00fcr Harzverkapselung<\/strong><\/p>\n<p style=\"text-align: justify;\">Die Implementierung einer Linie zur Verkapselung von elektronischen Schaltungen ist eine Investition, die f\u00fcr die Hersteller von elektronischen Ger\u00e4ten nicht immer gerechtfertigt ist.<\/p>\n<p style=\"text-align: justify;\">Dieser Vorgang kann mit hohen Risiken verbunden sein (insbesondere, wenn er mit den am weitesten verbreiteten Ger\u00e4ten der mittleren\/niedrigen Klasse durchgef\u00fchrt wird) und erfordert technische Erfahrung sowie das Management von gesundheitlichen und \u00f6kologischen Aspekten usw.<\/p>\n<p style=\"text-align: justify;\">Dank unserer drei\u00dfigj\u00e4hrigen Erfahrung sind wir in der Lage, diesen Service f\u00fcr Dritte zu geringen Kosten (dank des hohen Automatisierungsgrades) und mit hoher Qualit\u00e4t, die durch eine st\u00e4ndige \u00dcberwachung der Harzmischung und des Prozesses garantiert wird, anzubieten.<\/p>\n<p>[\/vc_column_text][dfd_spacer screen_wide_spacer_size=&#8221;60&#8243; screen_normal_resolution=&#8221;1024&#8243; screen_tablet_resolution=&#8221;800&#8243; screen_mobile_resolution=&#8221;480&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][dfd_spacer screen_wide_spacer_size=&#8221;50&#8243; screen_normal_resolution=&#8221;1024&#8243; screen_tablet_resolution=&#8221;800&#8243; screen_mobile_resolution=&#8221;480&#8243;][dfd_single_image image=&#8221;17592&#8243;][dfd_spacer screen_wide_spacer_size=&#8221;60&#8243; screen_normal_resolution=&#8221;1024&#8243; screen_tablet_resolution=&#8221;800&#8243; screen_mobile_resolution=&#8221;480&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][dfd_modal_box display_options=&#8221;on_click&#8221; button_text=&#8221;Stellen Sie Ihre Anfrage&#8221; modal_box_width=&#8221;400&#8243; box_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; hover_box_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221;]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f19102-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"19102\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/pages\/14912#wpcf7-f19102-o1\" method=\"post\" class=\"wpcf7-form init wpcf7-acceptance-as-validation\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"19102\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f19102-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.5\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div id=\"responsive-form\" class=\"clearfix\">\n\t<div class=\"form-row\">\n\t\t<div class=\"column-half\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name (*)\" value=\"\" type=\"text\" name=\"nome\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-half\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"azienda\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Unternehmen (*)\" value=\"\" type=\"text\" name=\"azienda\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"form-row\">\n\t\t<div class=\"column-half\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email (*)\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-half\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telefon (*)\" value=\"\" type=\"tel\" name=\"telefono\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"form-row\">\n\t\t<div class=\"column-half\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"sito\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Website\" value=\"\" type=\"text\" name=\"sito\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-half\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Funzione\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"Funzione\"><option value=\"\">Position (*)<\/option><option value=\"Elektroniker\/in\">Elektroniker\/in<\/option><option value=\"Projektleiter\">Projektleiter<\/option><option value=\"Einkaufsverantwortlicher\">Einkaufsverantwortlicher<\/option><option value=\"Sonstiges\">Sonstiges<\/option><\/select><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"form-row\">\n\t\t<div class=\"column-full\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap oggetto\" data-name=\"oggetto\"><input type=\"text\" name=\"oggetto\" class=\"wpcf7-form-control wpcf7-text wpcf7dtx wpcf7dtx-text\" aria-invalid=\"false\" value=\"Dienstleistungen\"><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"form-row\">\n\t\t<div class=\"column-full\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Messaggio\"><textarea cols=\"40\" rows=\"4\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Ihre Anfrage\" name=\"Messaggio\"><\/textarea><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"form-row\">\n\t\t<div class=\"column-full\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"risonanti\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"risonanti[]\" value=\"Dokumentationsauftrag f\u00fcr integrierte Standard-Resonanztransformatoren\" \/><span class=\"wpcf7-list-item-label\">Dokumentationsauftrag f\u00fcr integrierte Standard-Resonanztransformatoren<\/span><\/span><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"form-row\">\n\t\t<div class=\"column-full\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"catalogo\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"catalogo[]\" value=\"Vollst\u00e4ndiger Katalog anfordern\" \/><span class=\"wpcf7-list-item-label\">Vollst\u00e4ndiger Katalog anfordern<\/span><\/span><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"form-row\">\n\t\t<div class=\"column-full\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"newsletter\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"newsletter[]\" value=\"den Newsletter abonnieren\" \/><span class=\"wpcf7-list-item-label\">den Newsletter abonnieren<\/span><\/span><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"form-row\">\n\t\t<div class=\"column-full\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acconsento\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acconsento\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Zustimmung zur <a href=\"https:\/\/itacoilweb.com\/files\/DP_ENG_privacy.pdf\" target=\"_blank\">Datenverarbeitung<\/a> (*)<\/span><\/label><\/span><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"form-row\">\n\t\t<div class=\"column-full\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><!--end responsive-form--><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/dfd_modal_box][dfd_spacer screen_wide_spacer_size=&#8221;80&#8243; screen_normal_resolution=&#8221;1024&#8243; screen_tablet_resolution=&#8221;800&#8243; screen_mobile_resolution=&#8221;480&#8243; tutorials=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][dfd_delimiter delimiter_style=&#8221;dfd-delimiter-with-text&#8221; text_delimiter=&#8221;Siehe auch&#8221; title_font_options=&#8221;font_size:20|font_style_bold:1&#8243;][dfd_spacer screen_wide_spacer_size=&#8221;30&#8243; screen_normal_resolution=&#8221;1024&#8243; screen_tablet_resolution=&#8221;800&#8243; screen_mobile_resolution=&#8221;480&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.itacoilweb.com\/de\/produkte\/\" rel=\"noopener\">Produkte<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.itacoilweb.com\/de\/portfolio_category\/demo-boards-de\/\" rel=\"noopener\">Demo-Boards<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.itacoilweb.com\/de\/qualitaet-und-konformitaet\/forschung-und-entwicklung\/\" rel=\"noopener\">Forschung und Entwicklung<\/a><\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][dfd_spacer screen_wide_spacer_size=&#8221;50&#8243; screen_normal_resolution=&#8221;1024&#8243; screen_tablet_resolution=&#8221;800&#8243; screen_mobile_resolution=&#8221;480&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][dfd_heading style=&#8221;style_09&#8243; subtitle=&#8221;&#8221; content_alignment=&#8221;text-left&#8221; module_animation=&#8221;transition.slideRightBigIn&#8221; delimiter_settings=&#8221;delimiter_style:solid|delimiter_width:80|delimiter_height:1&#8243; undefined=&#8221;&#8221; title_font_options=&#8221;tag:h2&#8243; subtitle_font_options=&#8221;tag:div&#8221;] Dienstleistungen [\/dfd_heading][dfd_spacer screen_wide_spacer_size=&#8221;30&#8243; screen_normal_resolution=&#8221;1024&#8243; screen_tablet_resolution=&#8221;800&#8243; screen_mobile_resolution=&#8221;480&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text] Kundenspezifische Komponenten Mit einzigartigen propriet\u00e4ren Werkzeugen f\u00fcr Design und Simulation wird die Entwurfszeit auf ein<\/p>\n","protected":false},"author":10,"featured_media":17630,"parent":0,"menu_order":42,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-14912","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dienstleistungen - ITACOIL transformers<\/title>\n<meta name=\"description\" content=\"Kundenspezifische Komponenten, Sicherheits- und EMC-Vorkonformit\u00e4t, Tests, Schnelles Prototyping, Service f\u00fcr Harzverkapselung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itacoilweb.com\/de\/dienstleistungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dienstleistungen\" \/>\n<meta property=\"og:description\" content=\"Kundenspezifische Komponenten, Sicherheits- und EMC-Vorkonformit\u00e4t, Tests, Schnelles Prototyping, Service f\u00fcr Harzverkapselung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itacoilweb.com\/de\/dienstleistungen\/\" \/>\n<meta property=\"og:site_name\" content=\"ITACOIL transformers\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-17T15:29:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itacoilweb.com\/remo\/wp-content\/uploads\/IMG_3264-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itacoilweb.com\\\/de\\\/dienstleistungen\\\/\",\"url\":\"https:\\\/\\\/www.itacoilweb.com\\\/de\\\/dienstleistungen\\\/\",\"name\":\"Dienstleistungen - ITACOIL transformers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itacoilweb.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itacoilweb.com\\\/de\\\/dienstleistungen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itacoilweb.com\\\/de\\\/dienstleistungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itacoilweb.com\\\/remo\\\/wp-content\\\/uploads\\\/IMG_3264-1.png\",\"datePublished\":\"2020-02-25T08:50:58+00:00\",\"dateModified\":\"2024-06-17T15:29:48+00:00\",\"description\":\"Kundenspezifische Komponenten, Sicherheits- und EMC-Vorkonformit\u00e4t, Tests, Schnelles Prototyping, Service f\u00fcr Harzverkapselung.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itacoilweb.com\\\/de\\\/dienstleistungen\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itacoilweb.com\\\/de\\\/dienstleistungen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.itacoilweb.com\\\/de\\\/dienstleistungen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itacoilweb.com\\\/remo\\\/wp-content\\\/uploads\\\/IMG_3264-1.png\",\"contentUrl\":\"https:\\\/\\\/www.itacoilweb.com\\\/remo\\\/wp-content\\\/uploads\\\/IMG_3264-1.png\",\"width\":600,\"height\":450,\"caption\":\"Itacoil lab instruments example\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itacoilweb.com\\\/de\\\/dienstleistungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.itacoilweb.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dienstleistungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itacoilweb.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.itacoilweb.com\\\/de\\\/\",\"name\":\"ITACOIL transformers\",\"description\":\"PCB transformers and Inductors\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itacoilweb.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itacoilweb.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itacoilweb.com\\\/de\\\/#organization\",\"name\":\"ITACOIL Transformers\",\"url\":\"https:\\\/\\\/www.itacoilweb.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.itacoilweb.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itacoilweb.com\\\/remo\\\/wp-content\\\/uploads\\\/image\\\/png\\\/ITACOIL-logo2018-RTG-48.png\",\"contentUrl\":\"https:\\\/\\\/www.itacoilweb.com\\\/remo\\\/wp-content\\\/uploads\\\/image\\\/png\\\/ITACOIL-logo2018-RTG-48.png\",\"width\":151,\"height\":48,\"caption\":\"ITACOIL Transformers\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itacoilweb.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/itacoil\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ITACOILtrasformatori\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dienstleistungen - ITACOIL transformers","description":"Kundenspezifische Komponenten, Sicherheits- und EMC-Vorkonformit\u00e4t, Tests, Schnelles Prototyping, Service f\u00fcr Harzverkapselung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itacoilweb.com\/de\/dienstleistungen\/","og_locale":"de_DE","og_type":"article","og_title":"Dienstleistungen","og_description":"Kundenspezifische Komponenten, Sicherheits- und EMC-Vorkonformit\u00e4t, Tests, Schnelles Prototyping, Service f\u00fcr Harzverkapselung.","og_url":"https:\/\/www.itacoilweb.com\/de\/dienstleistungen\/","og_site_name":"ITACOIL transformers","article_modified_time":"2024-06-17T15:29:48+00:00","og_image":[{"width":600,"height":450,"url":"https:\/\/www.itacoilweb.com\/remo\/wp-content\/uploads\/IMG_3264-1.png","type":"image\/png"}],"twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.itacoilweb.com\/de\/dienstleistungen\/","url":"https:\/\/www.itacoilweb.com\/de\/dienstleistungen\/","name":"Dienstleistungen - ITACOIL transformers","isPartOf":{"@id":"https:\/\/www.itacoilweb.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itacoilweb.com\/de\/dienstleistungen\/#primaryimage"},"image":{"@id":"https:\/\/www.itacoilweb.com\/de\/dienstleistungen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itacoilweb.com\/remo\/wp-content\/uploads\/IMG_3264-1.png","datePublished":"2020-02-25T08:50:58+00:00","dateModified":"2024-06-17T15:29:48+00:00","description":"Kundenspezifische Komponenten, Sicherheits- und EMC-Vorkonformit\u00e4t, Tests, Schnelles Prototyping, Service f\u00fcr Harzverkapselung.","breadcrumb":{"@id":"https:\/\/www.itacoilweb.com\/de\/dienstleistungen\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itacoilweb.com\/de\/dienstleistungen\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.itacoilweb.com\/de\/dienstleistungen\/#primaryimage","url":"https:\/\/www.itacoilweb.com\/remo\/wp-content\/uploads\/IMG_3264-1.png","contentUrl":"https:\/\/www.itacoilweb.com\/remo\/wp-content\/uploads\/IMG_3264-1.png","width":600,"height":450,"caption":"Itacoil lab instruments example"},{"@type":"BreadcrumbList","@id":"https:\/\/www.itacoilweb.com\/de\/dienstleistungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.itacoilweb.com\/de\/"},{"@type":"ListItem","position":2,"name":"Dienstleistungen"}]},{"@type":"WebSite","@id":"https:\/\/www.itacoilweb.com\/de\/#website","url":"https:\/\/www.itacoilweb.com\/de\/","name":"ITACOIL transformers","description":"PCB transformers and Inductors","publisher":{"@id":"https:\/\/www.itacoilweb.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itacoilweb.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.itacoilweb.com\/de\/#organization","name":"ITACOIL Transformers","url":"https:\/\/www.itacoilweb.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.itacoilweb.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.itacoilweb.com\/remo\/wp-content\/uploads\/image\/png\/ITACOIL-logo2018-RTG-48.png","contentUrl":"https:\/\/www.itacoilweb.com\/remo\/wp-content\/uploads\/image\/png\/ITACOIL-logo2018-RTG-48.png","width":151,"height":48,"caption":"ITACOIL Transformers"},"image":{"@id":"https:\/\/www.itacoilweb.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/itacoil\/","https:\/\/www.youtube.com\/user\/ITACOILtrasformatori"]}]}},"_links":{"self":[{"href":"https:\/\/www.itacoilweb.com\/de\/wp-json\/wp\/v2\/pages\/14912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itacoilweb.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.itacoilweb.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.itacoilweb.com\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itacoilweb.com\/de\/wp-json\/wp\/v2\/comments?post=14912"}],"version-history":[{"count":20,"href":"https:\/\/www.itacoilweb.com\/de\/wp-json\/wp\/v2\/pages\/14912\/revisions"}],"predecessor-version":[{"id":20426,"href":"https:\/\/www.itacoilweb.com\/de\/wp-json\/wp\/v2\/pages\/14912\/revisions\/20426"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itacoilweb.com\/de\/wp-json\/wp\/v2\/media\/17630"}],"wp:attachment":[{"href":"https:\/\/www.itacoilweb.com\/de\/wp-json\/wp\/v2\/media?parent=14912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}